{"id":174,"date":"2025-04-17T20:31:02","date_gmt":"2025-04-17T20:31:02","guid":{"rendered":"https:\/\/elalmacendelaweb.com.ar\/jotatec\/?p=174"},"modified":"2025-04-17T20:31:02","modified_gmt":"2025-04-17T20:31:02","slug":"jotatec-incorporo-paneles-solares-para-proveerse-de-energia","status":"publish","type":"post","link":"https:\/\/jotatec.com\/en\/jotatec-incorporo-paneles-solares-para-proveerse-de-energia\/","title":{"rendered":"Jotatec incorpor\u00f3 paneles solares para proveerse de energ\u00eda"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" class=\"wp-image-5696\" src=\"http:\/\/www.jotatec.com\/wp-content\/uploads\/2020\/12\/Paneles-Solares-Jotatec-edited.jpeg\" alt=\"\" \/><\/figure>\n<p>La empresa instal\u00f3 en su lab de Buenos Aires esta fuente de energ\u00eda renovable para su funcionamiento diario.<\/p>\n<p>Con el objetivo de reducir las emisiones y optar por fuentes de energ\u00edas limpias, Jotatec, l\u00edder en tecnolog\u00eda aplicada a la medicina, decidi\u00f3 incorporar paneles solares en el techo de la f\u00e1brica que funciona en el barrio porte\u00f1o de Saavedra.<\/p>\n<p>Para eso, contrat\u00f3 a Renovar Energ\u00edas, que provee el servicio. A trav\u00e9s de este sistema, Jotatec reduce los consumos de la red el\u00e9ctrica, generando energ\u00eda que es consumida en el lugar, o, en caso de que no haya consumos, pueda ser inyectada a la red.<\/p>\n<p>&nbsp;<\/p>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" class=\"wp-image-5698\" src=\"http:\/\/www.jotatec.com\/wp-content\/uploads\/2020\/12\/Paneles-solares-Jotatec-2-1067x800.jpeg\" alt=\"\" \/><\/figure>\n<p>Mediante la instalaci\u00f3n de un inversor de corriente, la energ\u00eda generada por los paneles en forma de corriente continua (CC), es transformada en corriente alterna (CA), e inyectada en el tablero general del edificio. Desde all\u00ed, la energ\u00eda circular\u00e1 hacia los consumos de forma conjunta con la energ\u00eda de red, y s\u00f3lo en los casos en que la potencia de generaci\u00f3n solar supere a los consumos, la energ\u00eda fluir\u00e1 hacia la red.<\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; La empresa instal\u00f3 en su lab de Buenos Aires esta fuente de energ\u00eda renovable para su funcionamiento diario. Con el objetivo de reducir las emisiones y optar por fuentes de energ\u00edas limpias, Jotatec, l\u00edder en tecnolog\u00eda aplicada a la medicina, decidi\u00f3 incorporar paneles solares en el techo de la f\u00e1brica que funciona en el [&hellip;]<\/p>","protected":false},"author":1,"featured_media":175,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/jotatec.com\/en\/wp-json\/wp\/v2\/posts\/174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jotatec.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jotatec.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jotatec.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jotatec.com\/en\/wp-json\/wp\/v2\/comments?post=174"}],"version-history":[{"count":1,"href":"https:\/\/jotatec.com\/en\/wp-json\/wp\/v2\/posts\/174\/revisions"}],"predecessor-version":[{"id":176,"href":"https:\/\/jotatec.com\/en\/wp-json\/wp\/v2\/posts\/174\/revisions\/176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jotatec.com\/en\/wp-json\/wp\/v2\/media\/175"}],"wp:attachment":[{"href":"https:\/\/jotatec.com\/en\/wp-json\/wp\/v2\/media?parent=174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jotatec.com\/en\/wp-json\/wp\/v2\/categories?post=174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jotatec.com\/en\/wp-json\/wp\/v2\/tags?post=174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}